{"id":14229,"date":"2023-03-02T13:00:42","date_gmt":"2023-03-02T12:00:42","guid":{"rendered":"https:\/\/botiss.com\/product\/botisscare-d3k2\/"},"modified":"2023-11-02T12:23:05","modified_gmt":"2023-11-02T11:23:05","slug":"botisscare-d3k2-alt","status":"publish","type":"product","link":"https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/","title":{"rendered":"botissCARE D3+K2 ALT"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":16258,"template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"product_brand":[],"product_cat":[606],"product_tag":[607],"class_list":["post-14229","product","type-product","status-publish","has-post-thumbnail","product_cat-botisscare-de","product_tag-botiss-care-de","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>botissCARE D3+K2 ALT - botiss biomaterials GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"botissCARE D3+K2 ALT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/\" \/>\n<meta property=\"og:site_name\" content=\"botiss biomaterials GmbH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/botissdental\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-02T11:23:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/botiss.com\/wp-content\/uploads\/2023\/03\/botissCARE_D3K2_1200x800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BotissB\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/botiss.com\\\/de\\\/produkt\\\/botisscare-d3k2-alt\\\/\",\"url\":\"https:\\\/\\\/botiss.com\\\/de\\\/produkt\\\/botisscare-d3k2-alt\\\/\",\"name\":\"botissCARE D3+K2 ALT - botiss biomaterials GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/botiss.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/botiss.com\\\/de\\\/produkt\\\/botisscare-d3k2-alt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/botiss.com\\\/de\\\/produkt\\\/botisscare-d3k2-alt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/botiss.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/botissCARE_D3K2_1200x800.jpg\",\"datePublished\":\"2023-03-02T12:00:42+00:00\",\"dateModified\":\"2023-11-02T11:23:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/botiss.com\\\/de\\\/produkt\\\/botisscare-d3k2-alt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/botiss.com\\\/de\\\/produkt\\\/botisscare-d3k2-alt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/botiss.com\\\/de\\\/produkt\\\/botisscare-d3k2-alt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/botiss.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/botissCARE_D3K2_1200x800.jpg\",\"contentUrl\":\"https:\\\/\\\/botiss.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/botissCARE_D3K2_1200x800.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/botiss.com\\\/de\\\/produkt\\\/botisscare-d3k2-alt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/botiss.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/botiss.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"botissCARE D3+K2 ALT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/botiss.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/botiss.com\\\/de\\\/\",\"name\":\"botiss biomaterials GmbH\",\"description\":\"Driving dental innovation\",\"publisher\":{\"@id\":\"https:\\\/\\\/botiss.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/botiss.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/botiss.com\\\/de\\\/#organization\",\"name\":\"botiss medical AG\",\"alternateName\":\"botiss medical AG\",\"url\":\"https:\\\/\\\/botiss.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/botiss.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/botiss.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/botiss_logo_rgb.svg\",\"contentUrl\":\"https:\\\/\\\/botiss.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/botiss_logo_rgb.svg\",\"width\":225,\"height\":105,\"caption\":\"botiss medical AG\"},\"image\":{\"@id\":\"https:\\\/\\\/botiss.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/botissdental\",\"https:\\\/\\\/x.com\\\/BotissB\",\"https:\\\/\\\/www.instagram.com\\\/botiss_dental\\\/?__coig_restricted=1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/botiss-biomaterials\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@botissbiomaterials\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"botissCARE D3+K2 ALT - botiss biomaterials GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/","og_locale":"de_DE","og_type":"article","og_title":"botissCARE D3+K2 ALT","og_url":"https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/","og_site_name":"botiss biomaterials GmbH","article_publisher":"https:\/\/www.facebook.com\/botissdental","article_modified_time":"2023-11-02T11:23:05+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/botiss.com\/wp-content\/uploads\/2023\/03\/botissCARE_D3K2_1200x800.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@BotissB","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/","url":"https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/","name":"botissCARE D3+K2 ALT - botiss biomaterials GmbH","isPartOf":{"@id":"https:\/\/botiss.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/#primaryimage"},"image":{"@id":"https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/#primaryimage"},"thumbnailUrl":"https:\/\/botiss.com\/wp-content\/uploads\/2023\/03\/botissCARE_D3K2_1200x800.jpg","datePublished":"2023-03-02T12:00:42+00:00","dateModified":"2023-11-02T11:23:05+00:00","breadcrumb":{"@id":"https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/#primaryimage","url":"https:\/\/botiss.com\/wp-content\/uploads\/2023\/03\/botissCARE_D3K2_1200x800.jpg","contentUrl":"https:\/\/botiss.com\/wp-content\/uploads\/2023\/03\/botissCARE_D3K2_1200x800.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/botiss.com\/de\/produkt\/botisscare-d3k2-alt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/botiss.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/botiss.com\/shop\/"},{"@type":"ListItem","position":3,"name":"botissCARE D3+K2 ALT"}]},{"@type":"WebSite","@id":"https:\/\/botiss.com\/de\/#website","url":"https:\/\/botiss.com\/de\/","name":"botiss biomaterials GmbH","description":"Driving dental innovation","publisher":{"@id":"https:\/\/botiss.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/botiss.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/botiss.com\/de\/#organization","name":"botiss medical AG","alternateName":"botiss medical AG","url":"https:\/\/botiss.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/botiss.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/botiss.com\/wp-content\/uploads\/2022\/10\/botiss_logo_rgb.svg","contentUrl":"https:\/\/botiss.com\/wp-content\/uploads\/2022\/10\/botiss_logo_rgb.svg","width":225,"height":105,"caption":"botiss medical AG"},"image":{"@id":"https:\/\/botiss.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/botissdental","https:\/\/x.com\/BotissB","https:\/\/www.instagram.com\/botiss_dental\/?__coig_restricted=1","https:\/\/www.linkedin.com\/company\/botiss-biomaterials\/","https:\/\/www.youtube.com\/@botissbiomaterials"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 20:34:07","action":"category-add","newStatus":"draft","terms":[0],"taxonomy":"product_cat","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/botiss.com\/de\/wp-json\/wp\/v2\/product\/14229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/botiss.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/botiss.com\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/botiss.com\/de\/wp-json\/wp\/v2\/product\/14229\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/botiss.com\/de\/wp-json\/wp\/v2\/media\/16258"}],"wp:attachment":[{"href":"https:\/\/botiss.com\/de\/wp-json\/wp\/v2\/media?parent=14229"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/botiss.com\/de\/wp-json\/wp\/v2\/product_brand?post=14229"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/botiss.com\/de\/wp-json\/wp\/v2\/product_cat?post=14229"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/botiss.com\/de\/wp-json\/wp\/v2\/product_tag?post=14229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}